{"id":1994,"count":10,"description":"","link":"https:\/\/empire-music.net\/index.php\/tag\/relationship\/","name":"relationship","slug":"relationship","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags\/1994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/posts?tags=1994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}