{"id":2695,"count":3,"description":"","link":"https:\/\/empire-music.net\/index.php\/tag\/potent\/","name":"potent","slug":"potent","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags\/2695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/posts?tags=2695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}