{"id":2737,"count":3,"description":"","link":"https:\/\/empire-music.net\/index.php\/tag\/reviews\/","name":"reviews","slug":"reviews","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags\/2737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/posts?tags=2737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}