{"id":351,"count":2,"description":"","link":"https:\/\/empire-music.net\/index.php\/tag\/paco\/","name":"paco","slug":"paco","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags\/351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/posts?tags=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}