{"id":6548,"count":1,"description":"","link":"https:\/\/empire-music.net\/index.php\/tag\/hennessy\/","name":"hennessy","slug":"hennessy","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags\/6548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/empire-music.net\/index.php\/wp-json\/wp\/v2\/posts?tags=6548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}